{"id":62,"date":"2015-05-13T14:34:32","date_gmt":"2015-05-13T14:34:32","guid":{"rendered":"http:\/\/visitedemarseille.com\/visite\/?page_id=62"},"modified":"2022-12-05T15:32:41","modified_gmt":"2022-12-05T14:32:41","slug":"contact","status":"publish","type":"page","link":"https:\/\/visitedemarseille.com\/visite\/contact\/","title":{"rendered":"Contact"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"62\" class=\"elementor elementor-62\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5c6635f0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5c6635f0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-73c5ac26\" data-id=\"73c5ac26\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-20126a38 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"20126a38\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">contact &amp; devis<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-477ad75a elementor-widget elementor-widget-heading\" data-id=\"477ad75a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Justine Coste, guide conf\u00e9renci\u00e8re<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-841c4d2 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"841c4d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:600}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Vous souhaitez des renseignements compl\u00e9mentaires sur une visite ou sur une conf\u00e9rence? Un devis?<\/p><p><strong>Contactez-moi directement :<\/strong><\/p><p>\u00a0Par t\u00e9l\u00e9phone au +33 (0)6 62 65 58 19<\/p><p>Par mail : contact@visitedemarseille.com<\/p><p style=\"text-align: center;\">A bient\u00f4t!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-081a36f elementor-hidden-tablet elementor-hidden-mobile elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"081a36f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:600}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><img decoding=\"async\" class=\"wp-image-5634 alignright\" src=\"https:\/\/visitedemarseille.com\/visite\/wp-content\/uploads\/2022\/10\/Group-5-1-1.png\" alt=\"petites \" width=\"200\" height=\"201\" srcset=\"https:\/\/visitedemarseille.com\/visite\/wp-content\/uploads\/2022\/10\/Group-5-1-1.png 221w, https:\/\/visitedemarseille.com\/visite\/wp-content\/uploads\/2022\/10\/Group-5-1-1-199x200.png 199w, https:\/\/visitedemarseille.com\/visite\/wp-content\/uploads\/2022\/10\/Group-5-1-1-150x150.png 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/p><p style=\"text-align: center;\">\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f55f13a\" data-id=\"f55f13a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-56e73d46 elementor-widget elementor-widget-image\" data-id=\"56e73d46\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/visitedemarseille.com\/visite\/wp-content\/uploads\/2022\/12\/contact-2-2-1024x1024.png\" class=\"attachment-large size-large wp-image-7506\" alt=\"\" srcset=\"https:\/\/visitedemarseille.com\/visite\/wp-content\/uploads\/2022\/12\/contact-2-2-1024x1024.png 1024w, https:\/\/visitedemarseille.com\/visite\/wp-content\/uploads\/2022\/12\/contact-2-2-200x200.png 200w, https:\/\/visitedemarseille.com\/visite\/wp-content\/uploads\/2022\/12\/contact-2-2-150x150.png 150w, https:\/\/visitedemarseille.com\/visite\/wp-content\/uploads\/2022\/12\/contact-2-2-768x768.png 768w, https:\/\/visitedemarseille.com\/visite\/wp-content\/uploads\/2022\/12\/contact-2-2.png 1064w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>contact &#038; devis Justine Coste, guide conf\u00e9renci\u00e8re Vous souhaitez des renseignements compl\u00e9mentaires sur une visite ou sur une conf\u00e9rence? Un devis? Contactez-moi directement : \u00a0Par t\u00e9l\u00e9phone au +33 (0)6 62 65 58 19 Par mail : contact@visitedemarseille.com A bient\u00f4t! \u00a0<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"class_list":["post-62","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Contact - Visite de Marseille<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/visitedemarseille.com\/visite\/contact\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contact - Visite de Marseille\" \/>\n<meta property=\"og:description\" content=\"contact &#038; devis Justine Coste, guide conf\u00e9renci\u00e8re Vous souhaitez des renseignements compl\u00e9mentaires sur une visite ou sur une conf\u00e9rence? Un devis? Contactez-moi directement : \u00a0Par t\u00e9l\u00e9phone au +33 (0)6 62 65 58 19 Par mail : contact@visitedemarseille.com A bient\u00f4t! \u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/visitedemarseille.com\/visite\/contact\/\" \/>\n<meta property=\"og:site_name\" content=\"Visite de Marseille\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Visitedemarseille\/\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-05T14:32:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/visitedemarseille.com\/visite\/wp-content\/uploads\/2022\/10\/Group-5-1-1.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/visitedemarseille.com\\\/visite\\\/contact\\\/\",\"url\":\"https:\\\/\\\/visitedemarseille.com\\\/visite\\\/contact\\\/\",\"name\":\"Contact - Visite de Marseille\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/visitedemarseille.com\\\/visite\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/visitedemarseille.com\\\/visite\\\/contact\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/visitedemarseille.com\\\/visite\\\/contact\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/visitedemarseille.com\\\/visite\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Group-5-1-1.png\",\"datePublished\":\"2015-05-13T14:34:32+00:00\",\"dateModified\":\"2022-12-05T14:32:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/visitedemarseille.com\\\/visite\\\/contact\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/visitedemarseille.com\\\/visite\\\/contact\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/visitedemarseille.com\\\/visite\\\/contact\\\/#primaryimage\",\"url\":\"https:\\\/\\\/visitedemarseille.com\\\/visite\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Group-5-1-1.png\",\"contentUrl\":\"https:\\\/\\\/visitedemarseille.com\\\/visite\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Group-5-1-1.png\",\"width\":221,\"height\":222,\"caption\":\"petites\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/visitedemarseille.com\\\/visite\\\/contact\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/visitedemarseille.com\\\/visite\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contact\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/visitedemarseille.com\\\/visite\\\/#website\",\"url\":\"https:\\\/\\\/visitedemarseille.com\\\/visite\\\/\",\"name\":\"Visite de Marseille\",\"description\":\"visites scolaires|conf\u00e9rences Marseillaises| animations seniors\",\"publisher\":{\"@id\":\"https:\\\/\\\/visitedemarseille.com\\\/visite\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/visitedemarseille.com\\\/visite\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/visitedemarseille.com\\\/visite\\\/#organization\",\"name\":\"Visite de Marseille\",\"url\":\"https:\\\/\\\/visitedemarseille.com\\\/visite\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/visitedemarseille.com\\\/visite\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/visitedemarseille.com\\\/visite\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/3.png\",\"contentUrl\":\"https:\\\/\\\/visitedemarseille.com\\\/visite\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/3.png\",\"width\":1200,\"height\":600,\"caption\":\"Visite de Marseille\"},\"image\":{\"@id\":\"https:\\\/\\\/visitedemarseille.com\\\/visite\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Visitedemarseille\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contact - Visite de Marseille","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/visitedemarseille.com\/visite\/contact\/","og_locale":"fr_FR","og_type":"article","og_title":"Contact - Visite de Marseille","og_description":"contact &#038; devis Justine Coste, guide conf\u00e9renci\u00e8re Vous souhaitez des renseignements compl\u00e9mentaires sur une visite ou sur une conf\u00e9rence? Un devis? Contactez-moi directement : \u00a0Par t\u00e9l\u00e9phone au +33 (0)6 62 65 58 19 Par mail : contact@visitedemarseille.com A bient\u00f4t! \u00a0","og_url":"https:\/\/visitedemarseille.com\/visite\/contact\/","og_site_name":"Visite de Marseille","article_publisher":"https:\/\/www.facebook.com\/Visitedemarseille\/","article_modified_time":"2022-12-05T14:32:41+00:00","og_image":[{"url":"https:\/\/visitedemarseille.com\/visite\/wp-content\/uploads\/2022\/10\/Group-5-1-1.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/visitedemarseille.com\/visite\/contact\/","url":"https:\/\/visitedemarseille.com\/visite\/contact\/","name":"Contact - Visite de Marseille","isPartOf":{"@id":"https:\/\/visitedemarseille.com\/visite\/#website"},"primaryImageOfPage":{"@id":"https:\/\/visitedemarseille.com\/visite\/contact\/#primaryimage"},"image":{"@id":"https:\/\/visitedemarseille.com\/visite\/contact\/#primaryimage"},"thumbnailUrl":"https:\/\/visitedemarseille.com\/visite\/wp-content\/uploads\/2022\/10\/Group-5-1-1.png","datePublished":"2015-05-13T14:34:32+00:00","dateModified":"2022-12-05T14:32:41+00:00","breadcrumb":{"@id":"https:\/\/visitedemarseille.com\/visite\/contact\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/visitedemarseille.com\/visite\/contact\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/visitedemarseille.com\/visite\/contact\/#primaryimage","url":"https:\/\/visitedemarseille.com\/visite\/wp-content\/uploads\/2022\/10\/Group-5-1-1.png","contentUrl":"https:\/\/visitedemarseille.com\/visite\/wp-content\/uploads\/2022\/10\/Group-5-1-1.png","width":221,"height":222,"caption":"petites"},{"@type":"BreadcrumbList","@id":"https:\/\/visitedemarseille.com\/visite\/contact\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/visitedemarseille.com\/visite\/"},{"@type":"ListItem","position":2,"name":"Contact"}]},{"@type":"WebSite","@id":"https:\/\/visitedemarseille.com\/visite\/#website","url":"https:\/\/visitedemarseille.com\/visite\/","name":"Visite de Marseille","description":"visites scolaires|conf\u00e9rences Marseillaises| animations seniors","publisher":{"@id":"https:\/\/visitedemarseille.com\/visite\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/visitedemarseille.com\/visite\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/visitedemarseille.com\/visite\/#organization","name":"Visite de Marseille","url":"https:\/\/visitedemarseille.com\/visite\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/visitedemarseille.com\/visite\/#\/schema\/logo\/image\/","url":"https:\/\/visitedemarseille.com\/visite\/wp-content\/uploads\/2022\/10\/3.png","contentUrl":"https:\/\/visitedemarseille.com\/visite\/wp-content\/uploads\/2022\/10\/3.png","width":1200,"height":600,"caption":"Visite de Marseille"},"image":{"@id":"https:\/\/visitedemarseille.com\/visite\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Visitedemarseille\/"]}]}},"_links":{"self":[{"href":"https:\/\/visitedemarseille.com\/visite\/wp-json\/wp\/v2\/pages\/62","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visitedemarseille.com\/visite\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/visitedemarseille.com\/visite\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/visitedemarseille.com\/visite\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/visitedemarseille.com\/visite\/wp-json\/wp\/v2\/comments?post=62"}],"version-history":[{"count":15,"href":"https:\/\/visitedemarseille.com\/visite\/wp-json\/wp\/v2\/pages\/62\/revisions"}],"predecessor-version":[{"id":7800,"href":"https:\/\/visitedemarseille.com\/visite\/wp-json\/wp\/v2\/pages\/62\/revisions\/7800"}],"wp:attachment":[{"href":"https:\/\/visitedemarseille.com\/visite\/wp-json\/wp\/v2\/media?parent=62"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}